{"id":7688,"date":"2020-07-29T14:13:06","date_gmt":"2020-07-29T12:13:06","guid":{"rendered":"http:\/\/galli.ch\/?post_type=uhren&#038;p=7688"},"modified":"2026-05-12T16:11:38","modified_gmt":"2026-05-12T14:11:38","slug":"hydroconquest-41-l3-781-4-06-6","status":"publish","type":"product","link":"https:\/\/galli.ch\/en\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/","title":{"rendered":"Longines Hydroconquest 41"},"content":{"rendered":"<p>Die Marke Longines nutzt ihre langj\u00e4hrige Erfahrung im Sportbereich und erweitert ihre Linie HydroConquest im 2018 um Varianten, die v\u00f6llig neu gestaltet worden sind. Die Uhren vereinen den technischen Anspruch und die traditionelle Eleganz, die der Marke mit der gefl\u00fcgelten Sanduhr so am Herzen liegen. Ihre L\u00fcnette ist mit farbiger Keramik veredelt, die ihr Glanz und Modernit\u00e4t verleiht. Die neuen edlen Modelle sind von der faszinierenden Welt des Wassersports inspiriert.<\/p>\n<p>Die HydroConquest Linie \u2013 Sportuhrenkollektion par excellence von Longines \u2013 wird den Anspr\u00fcchen aller gerecht, die die Weite des Ozeans lieben, und bleibt gleichzeitig der charakteristischen Eleganz der Schweizer Marke treu. Die HydroConquest Modelle greifen die Stilmittel des Tauchsports auf und lassen sich von den Anforderungen dieser Disziplin inspirieren. Merkmale wie eine Wasserdichtigkeit bis 300 Meter, die einseitig drehbare L\u00fcnette, ein verschraubter Boden und eine verschraubte Krone, der Kronenschutz sowie die Doppelsicherheitsfaltschliesse mit integrierter Tauchverl\u00e4ngerung unterstreichen den Charakter dieser Kollektion nachdr\u00fccklich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Marke Longines nutzt ihre langj\u00e4hrige Erfahrung im Sportbereich und erweitert ihre Linie HydroConquest im 2018 um Varianten, die v\u00f6llig neu gestaltet worden sind. Die Uhren vereinen den technischen Anspruch und die traditionelle Eleganz, die der Marke mit der gefl\u00fcgelten Sanduhr so am Herzen liegen. Ihre L\u00fcnette ist mit farbiger Keramik veredelt, die ihr Glanz&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.ch\/en\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/\" title=\"Read Longines Hydroconquest 41\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":7592,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":{"0":"post-7688","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"uhrenhersteller-longines","7":"uhrenhersteller-diving","8":"product_cat-uhren","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Longines Hydroconquest 41 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Longines Hydroconquest 41 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Marke Longines nutzt ihre langj\u00e4hrige Erfahrung im Sportbereich und erweitert ihre Linie HydroConquest im 2018 um Varianten, die v\u00f6llig neu gestaltet worden sind. Die Uhren vereinen den technischen Anspruch und die traditionelle Eleganz, die der Marke mit der gefl\u00fcgelten Sanduhr so am Herzen liegen. Ihre L\u00fcnette ist mit farbiger Keramik veredelt, die ihr Glanz... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T14:11:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.ch\/wp-content\/uploads\/L3-781-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/\",\"url\":\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/\",\"name\":\"Longines Hydroconquest 41 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"http:\/\/galli.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/galli.ch\/wp-content\/uploads\/L3-781-4.png\",\"datePublished\":\"2020-07-29T12:13:06+00:00\",\"dateModified\":\"2026-05-12T14:11:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#primaryimage\",\"url\":\"https:\/\/galli.ch\/wp-content\/uploads\/L3-781-4.png\",\"contentUrl\":\"https:\/\/galli.ch\/wp-content\/uploads\/L3-781-4.png\",\"width\":1000,\"height\":1400,\"caption\":\"longines-hydro-conquest-green\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/galli.ch\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\/\/galli.ch\/en\/uhren\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hydroconquest 41\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/galli.ch\/en\/#website\",\"url\":\"http:\/\/galli.ch\/en\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/galli.ch\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Longines Hydroconquest 41 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/","og_locale":"en_US","og_type":"article","og_title":"Longines Hydroconquest 41 - Galli Uhren Bijouterie","og_description":"Die Marke Longines nutzt ihre langj\u00e4hrige Erfahrung im Sportbereich und erweitert ihre Linie HydroConquest im 2018 um Varianten, die v\u00f6llig neu gestaltet worden sind. Die Uhren vereinen den technischen Anspruch und die traditionelle Eleganz, die der Marke mit der gefl\u00fcgelten Sanduhr so am Herzen liegen. Ihre L\u00fcnette ist mit farbiger Keramik veredelt, die ihr Glanz... Weiter &raquo;","og_url":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-05-12T14:11:38+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.ch\/wp-content\/uploads\/L3-781-4.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/","url":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/","name":"Longines Hydroconquest 41 - Galli Uhren Bijouterie","isPartOf":{"@id":"http:\/\/galli.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#primaryimage"},"image":{"@id":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.ch\/wp-content\/uploads\/L3-781-4.png","datePublished":"2020-07-29T12:13:06+00:00","dateModified":"2026-05-12T14:11:38+00:00","breadcrumb":{"@id":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#primaryimage","url":"https:\/\/galli.ch\/wp-content\/uploads\/L3-781-4.png","contentUrl":"https:\/\/galli.ch\/wp-content\/uploads\/L3-781-4.png","width":1000,"height":1400,"caption":"longines-hydro-conquest-green"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.ch\/uhren\/longines\/diving\/hydroconquest-41-l3-781-4-06-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.ch\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Hydroconquest 41"}]},{"@type":"WebSite","@id":"http:\/\/galli.ch\/en\/#website","url":"http:\/\/galli.ch\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/galli.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.ch\/en\/wp-json\/wp\/v2\/product\/7688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.ch\/en\/wp-json\/wp\/v2\/media\/7592"}],"wp:attachment":[{"href":"https:\/\/galli.ch\/en\/wp-json\/wp\/v2\/media?parent=7688"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.ch\/en\/wp-json\/wp\/v2\/product_brand?post=7688"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.ch\/en\/wp-json\/wp\/v2\/product_cat?post=7688"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.ch\/en\/wp-json\/wp\/v2\/product_tag?post=7688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}